{"id":8425,"date":"2019-04-19T17:23:00","date_gmt":"2019-04-19T17:23:00","guid":{"rendered":"https:\/\/cadus.madways.de\/unkategorisiert\/wie-war-das-noch-mit-den-menschenrechten\/"},"modified":"2019-04-19T17:23:00","modified_gmt":"2019-04-19T17:23:00","slug":"wie-war-das-noch-mit-den-menschenrechten","status":"publish","type":"post","link":"https:\/\/www.cadus.org\/en\/artikel\/wie-war-das-noch-mit-den-menschenrechten\/","title":{"rendered":"Wie war das noch mit den Menschenrechten?"},"content":{"rendered":"<div class=\"ce_text block\">\n<p><strong>Das Gefl\u00fcchtetenlager al-Hol in Nordostsyrien ist nach den K\u00e4mpfen gegen die letzten \u00dcberreste des IS komplett \u00fcberf\u00fcllt und jegliche Struktur \u00fcberlastet. Die gemeinsame Unterbringung von IS-Angeh\u00f6rigen und deren ehemaligen Opfern sorgt immer wieder f\u00fcr Konflikte unter den Bewohner*innen. Angesichts dessen stellt manche*r sich vielleicht die Fragen: Wie mit Verletzten oder Kranken umgehen, die sich \u00fcber jegliche Grundnormen menschlichen Zusammenlebens hinweggesetzt haben? Warum denen helfen, die m\u00f6glicherweise \u00fcber Jahre aus \u00dcberzeugung ein System unterst\u00fctzt haben, dass unglaublich viel Leid und Zerst\u00f6rung verursacht hat?<\/strong><span style=\"font-family: Arial, sans-serif;\"><span class=\"author-a-r9z84z9z70zz77znfz67zz67z5bcwz90zz80z\"><strong><br \/><\/strong><\/span><\/span><span class=\"author-a-r9z84z9z70zz77znfz67zz67z5bcwz90zz80z\"><br \/><\/span><span class=\"\">Die letzten R\u00fcckzugsorte des Islamischen Staates sind gefallen, lediglich <\/span><span class=\"author-a-r9z84z9z70zz77znfz67zz67z5bcwz90zz80z\">westlich des Euphrats halten knapp 3000 K\u00e4mpfer ein gering bev\u00f6lkertes Gebiet in der syrischen W\u00fcste.<br \/><\/span><span class=\"\">In den letzten zwei<\/span><span class=\"author-a-r9z84z9z70zz77znfz67zz67z5bcwz90zz80z\">einhalb<\/span><span class=\"\"> Monaten str\u00f6mten diejenigen, die sich ergaben oder geflohen sind, in ein Camp nahe der syrisch-irakischen Grenze. Frauen, Kinder und selten M\u00e4nner, unter ihnen auch wenige ehemalige K\u00e4mpfer. Das stellt die Bewohner*innen des 1991 ei<\/span><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\">n<\/span><span class=\"\">gerichteten Fl\u00fcchtlingscamps<\/span><span class=\"author-a-r9z84z9z70zz77znfz67zz67z5bcwz90zz80z\"> bei al-Hol <\/span><span class=\"\">aber auch die Menschen, die das Camp versorgen, vor besondere Belastungen. Teilweise treffen Opfer des IS auf ihre fr\u00fcheren Peiniger*innen, Menschen die unter der Herrschaft des IS litten versorgen nun die Angeh\u00f6rigen der K\u00e4mpfer. Hinzu kommt die schlechte Versorgungslage. Seit Beginn der K\u00e4mpfe um Baghuz haben sowohl die Zivilverwaltung in Nordostsyrien als auch lokale Hilfsorganisationen vor dem Szenario gewarnt, das jetzt eingetreten ist. <\/p>\n<p><strong>Tausende Menschen warten auf Versorgung<\/strong><\/p>\n<p><\/span><span class=\"\">Es fehlt vor Ort an Ressourcen um die mehr als 75.000 Personen im Camp al-Hol mehr als notd\u00fcrftig zu versorgen, die umliegenden Krankenh\u00e4user sind \u00fcber die Belastungsgrenze hinaus belegt, Helfer*innen sind teilweise 24 Stunden im Einsatz, die Kindersterblichkeit ist hoch. \u00dcberschwemmungen in der ganzen Region versch\u00e4rfen die ohnehin schon katastrophale Lage zus\u00e4tzlich.<\/p>\n<p><\/span><\/p>\n<p><span class=\"\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/12\/wie-war-das-noch-mit-den-menschenrechten-Wassertank20al-Hol202019.jpg\" alt=\"\"\/><em>Der Kern des Camps besteht schon seit dem Golfkrieg 1991 und besteht zum Teil aus festen H\u00fctten. Die alte Struktur muss f\u00fcr die Neuank\u00f6mmlinge massiv ausgebaut werden. \u00a9CADUS<\/em><br \/><\/span><\/p>\n<p><span class=\"\"><br \/><\/span><span class=\"\">Internationale Strukturen waren bis vor kurzem rar, erst langsam verst\u00e4rken UN-Organisationen und internationale NGOs ihr Engagement. Die Herausforderung, mehr als 45.000 teils dehydrierte, unterversorgte und unterk\u00fchlte Menschen innerhalb von zwei Wochen aufzunehmen, medizinisch zu versorgen, zu ern\u00e4hren und sicher unterzubringen h\u00e4tte auch gro\u00dfe Akteure vor eine Herausforderung gestellt. F\u00fcr lokale Hilfsorganisationen in einem Kriegsgebiet ist die Anzahl an zu versorgenden Menschen schlicht zu <\/span><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\">hoch<\/span><span class=\"\">. Das Lager bei al-Hol war ausgelegt f\u00fcr etwas \u00fcber 10.000 Personen, zus\u00e4tzliche Erweiterungen m\u00fcssen jetzt f\u00fcr gesch\u00e4tzte 76.000 Personen dienen, vieles ents<\/span><span class=\"author-a-r9z84z9z70zz77znfz67zz67z5bcwz90zz80z\">tand<\/span><span class=\"\"> w\u00e4hrend Leute von Baghuz in das 300 Kilometer entfernte al-Hol transportiert wurden.<br \/><\/span><span class=\"\">Ein Zustand, der so nicht l\u00e4nger tragbar war. Wir wurden angefragt, ob wir helfen k\u00f6nnen und haben <\/span><span class=\"author-a-r9z84z9z70zz77znfz67zz67z5bcwz90zz80z\">uns entschlossen<\/span><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\">,<\/span><span class=\"\"> die lokale Gesundheitsversorgung direkt im Camp zu unterst\u00fctzen<\/span><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\">,<\/span><span class=\"\"> um die umliegenden Krankenh\u00e4user zu entlasten und eine zeitnahe medizinische Versorgung Aller zu erm\u00f6glichen.<\/p>\n<p><strong>Medizinische Versorgung &#8211; ein Recht f\u00fcr jede*n?<\/strong><\/p>\n<p><\/span><span class=\"\">Medizinische Versorgung ist f\u00fcr uns ein Menschenrecht. Eines, das gerade im Kriegs- oder Konfliktfall vo<\/span><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\">n<\/span><span class=\"\"> elementarer Bedeutung ist und welches seit einigen Jahren leider ganz grunds\u00e4tzlich in Frage gestellt wird. Medizinisches Personal und unsere Einrichtungen genie\u00dfen l\u00e4ngst nicht mehr den Schutzstatus fr\u00fcherer bewaffneter Konflikte. Langj\u00e4hrige, teils grausam gef\u00fchrte Auseinandersetzungen stellen den hohen ethischen Anspruch aller Helfer*innen auf eine harte Probe. <br \/><\/span><span class=\"\">Wie mit Verletzten oder Kranken umgehen, die sich \u00fcber jegliche Grundnormen menschlichen Zusammenlebens hinweggesetzt haben?<\/span><span class=\"author-a-r9z84z9z70zz77znfz67zz67z5bcwz90zz80z\"> Warum denen helfen, die m\u00f6glicherweise \u00fcber Jahre aus \u00dcberzeugung ein System unterst\u00fctzt haben, dass unglaublich viel Leid und Zert\u00f6rung verursacht hat?<\/span> <span class=\"\">Die Fragen sind jeweils f\u00fcr sich hochkomplex, f\u00fcr uns steht aber ein einfacher Punkt immer fest: Wir behandeln jede Person, die unsere Hilfe sucht und braucht. Nicht immer mit einem Hochgef\u00fchl, sicher auch bei einigen F\u00e4llen mit Bauchschmerzen. Die Versorgung jeder Person ist jedoch ein so universales Recht, dass wir davon nicht abr\u00fccken wollen und k\u00f6nnen. Dabei ist f\u00fcr uns kein Widerspruch auch diejenigen zu behandeln, die mutma\u00dflich andere verfolgt, get\u00f6tet oder gefoltert haben. Teil des Wertekanons einer aufgekl\u00e4rten Gesellschaft muss es sein, auch denjenigen Menschenrechte und Grundbed\u00fcrfnisse zugestehen zu k\u00f6nnen, die eben diesen Wertekanon brechen. Alles andere artet in Willk\u00fcr aus.<\/p>\n<p><\/span><span class=\"\">Hilfsorganisationen sind nicht dazu gedacht, Schuld oder Unschuld festzustellen und darauf aufbauend zu bestrafen, daf\u00fcr existieren Gerichte. Diese zu schaffen ist angesichts der internationalen Tragweite der Herrschaft des IS Aufgabe der internationalen Gemeinschaft. Unsere Aufgabe und unser Anspruch ist es, dem universellen Menschenrecht auf medizinische Hilfe Geltung zu verschaffen indem wir auch die behandeln, die bis zuletzt freiwillig oder unter Zwang unter dem IS gelebt<\/span><span class=\"author-a-r9z84z9z70zz77znfz67zz67z5bcwz90zz80z\"> und gek\u00e4mpft<\/span><span class=\"\"> haben. <\/p>\n<p><\/span><span class=\"\">Kollektivstrafen sind in der j\u00fcngeren Geschichte Europas vor allem ein Ausdruck<\/span> <span class=\"\">entmenschlichter Politik gewesen, einer Politik die sich massiv mit unserem Werten und unserem Verst\u00e4ndnis einer besseren Gesellschaft bei\u00dft. Wenn wir gerade in Deutschland Kommentare h\u00f6ren, die Angeh\u00f6rigen der IS-K\u00e4mpfer h\u00e4tten ja gewusst worauf sie sich einlie\u00dfen und k\u00f6nnten gerne &#34;in der W\u00fcste verrotten&#34;, verschl\u00e4gt es uns ehrlich gesagt die Sprache. Das hat nichts mehr mit Freude \u00fcber das Ende des Kalifats oder dem Wunsch nach gerechter Bestrafung zu tun. Vielmehr tendiert es gef\u00e4hrlich <\/span><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\">in <\/span><span class=\"\">Richtung<\/span><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\"> von<\/span><span class=\"\"> Gewaltphantasien, die im \u00fcbrigen auch Ausdruck eines Menschenbildes sind, wie es der Islamische Staat vertritt. Humanit\u00e4re Hilfe kann nicht immer<\/span><span class=\"author-a-r9z84z9z70zz77znfz67zz67z5bcwz90zz80z\"> nur<\/span><span class=\"\"> denjenigen zu Gute kommen, die den eigenen Wertevorstellungen und Lebenskonzepten am <\/span><span class=\"author-a-r9z84z9z70zz77znfz67zz67z5bcwz90zz80z\">Besten entsprechen<\/span><span class=\"\">, gerade in bewaffneten Konflikten ist das schlicht unm\u00f6glich. Humanit\u00e4re Hilfe so wie wir sie verstehen ist universell, unabh\u00e4ngig von der Stellung der Person und ihrer Vergangenheit. <\/span><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\">Kurz gesagt: einzig und allein der Grad der Not z\u00e4hlt bei der Beurteilung, wer wie viel Hilfe bekommt.<\/p>\n<p><\/span><\/p>\n<p><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2023\/12\/wie-war-das-noch-mit-den-menschenrechten-KAR_05655B15D.jpg\" alt=\"\"\/><\/span><em><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\">Frauen und Kinder fliehen aus der umk\u00e4mpften Altstadt Mossuls im Irak 2017. Schon damals gab es Auseinandersetzungen dar\u00fcber, wie mit IS-Anh\u00e4nger*innen umzugehen w\u00e4re. Schnell wurden Menschen pauschal verurteilt Dschihadist*innen zu sein, nur weil sie nicht rechtzeitig fliehen konnten. \u00a9Kenny Karpov<\/span><\/em><\/p>\n<p><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\"><br \/><strong>Die Verantwortung der internationalen Gemeinschaft<\/strong><\/p>\n<p><\/span><span class=\"\">Gerade vor dem Hintergrund der Debatten um Strafverfolgung der ausl\u00e4ndischen IS-Kombatant*innen, bei der sich europ\u00e4ische Staaten aus der Aff\u00e4re ziehen wollen in dem sie einfach die Staatsb\u00fcrgerschaft entziehen, wird klar, dass das Thema leider weiter an die Menschen vor Ort &#34;ausgelagert&#34; werden soll. Sie versorgen ihre eigene Bev\u00f6lkerung, sollen IS-K\u00e4mpfer sowie Angeh\u00f6rige internieren und auf unbestimmte Zeit bis zu m\u00f6glichen Prozessen im Land behalten. Dabei haben sie sich an geltendes Recht zu halten und sollen mit den ohnehin schon knappen Ressourcen auch die ungef\u00e4hr 12.000 ausl\u00e4ndischen IS-K\u00e4mpfer medizinisch versorgen.<br \/><\/span><span class=\"\">Humanit\u00e4re Akteure haben seit langem kritisiert, dass solch eine Mehrfachbelastung nicht nur eine strukturelle Zumutung ist, sie ist auch nach allen Opfern welche die Menschen in Syrien und Irak im Kampf gegen den IS auf sich genommen haben, ein moralisches Totalversagen seitens der internationalen Staatengemeinschaft.<\/p>\n<p><strong>Ein Feldkrankenhaus f\u00fcr al-Hol<\/strong><\/p>\n<p><\/span><span class=\"\">Auf der (geo-) politischen Ebene werden wir als CADUS an diesem Zustand wenig \u00e4ndern k\u00f6nnen. Im Kleinen aber wollen wir etwas bewirken und das im Zusammenspiel mit den Menschen, die auch nach Ende des Kon<\/span><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\">f<\/span><span class=\"\">likts da bleiben und wieder in irgendeinder Form miteinander leben m\u00fcssen. F\u00fcr uns hei\u00dft das konkret: Wir bauen gemeinsam mit <\/span><span class=\"author-a-z73zw3z83zz89z9u7z87zz85z6xz76zz87z8e\">unserer Partnerorganisation <\/span><span class=\"\"> ein Krankenhaus im Camp auf, werden sowohl in beraterischer Funktion t\u00e4tig sein als auch Menschen direkt im laufenden Betrieb ausbilden. Das sichert eine nachhaltige medizinische Struktur, die in ganz Syrien bitter n\u00f6tig ist! Gleichzeitig wollen wir auch helfen, den akuten Notzustand zu verbessern. Das Krankenhaus im Camp wird in zwei Bauphasen entstehen und kann bei Fertigstellung 40 Patient*innen station\u00e4r versorgen. Labor, R\u00f6ntgen und Operationssaal inbegriffen. Der Aufbau von l\u00e4ngerfristigen Strukturen und die Inbetriebnahme eines Krankenhauses sind im Grenzbereich zwischen Nothilfe, wie wir sie verstehen, und klassischer Entwicklungszusammenarbeit angesiedelt. Angesichts der beschriebenen Umst\u00e4nde f\u00fcr uns aber Teil unseres Mandats zur akuten Unterst\u00fctzung bei gleichzeitigem Aufbau nachhaltiger Perspektiven. Mehr dazu in weiteren Beitr\u00e4gen.<\/p>\n<p><\/span><span class=\"\">Im Kleinen etwas bewirken hei\u00dft f\u00fcr uns auch, dass wir behutsam vor Ort arbeiten, die Spannungen die aufgrund des Konfliktes herrschen nicht noch verschlimmern und dabei als neutraler Partner f\u00fcr alle <\/span><span class=\"author-a-r9z84z9z70zz77znfz67zz67z5bcwz90zz80z\">aufzutreten<\/span><span class=\"\">. Das wird manchmal ein Drahtseilakt, aber auch eine Herausforderung derer wir uns als humanit\u00e4rer Organisation bewusst sind und der wir uns stellen.<\/span><\/p>\n<\/div>\n<div class=\"button-box ce_rsce_button   -centered\">\n<a class=\"button ce_rsce_button   -centered\" data-icon=\"\uf0f0\" href=\"https:\/\/www.betterplace.org\/de\/projects\/56993\/donations\/new#direct_deposit\" target=\"_blank\" rel=\"noopener\"><br \/>\nUnterst\u00fctze uns mit deiner Spende!\t<\/a>\n<\/div>\n<p class=\"info\">Ver\u00f6ffentlicht: <time datetime=\"2019-04-18T15:48:00+02:00\">18.04.2019<\/time><br \/>Verfasser*in:  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Gefl\u00fcchtetenlager al-Hol in Nordostsyrien ist nach den K\u00e4mpfen gegen die letzten \u00dcberreste des IS komplett \u00fcberf\u00fcllt und jegliche Struktur \u00fcberlastet. Die gemeinsame Unterbringung von IS-Angeh\u00f6rigen und deren ehemaligen Opfern sorgt immer wieder f\u00fcr Konflikte unter den Bewohner*innen. Angesichts dessen stellt \u2026<\/p>\n","protected":false},"author":7,"featured_media":8419,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[80,82],"tags":[],"class_list":["post-8425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artikel","category-blog"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/posts\/8425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/comments?post=8425"}],"version-history":[{"count":0,"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/posts\/8425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/media\/8419"}],"wp:attachment":[{"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/media?parent=8425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/categories?post=8425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/tags?post=8425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}