{"id":9179,"date":"2017-06-22T20:57:00","date_gmt":"2017-06-22T20:57:00","guid":{"rendered":"https:\/\/cadus.madways.de\/unkategorisiert\/humanitaere-lage-in-rojava-weiterhin-kritisch-interview\/"},"modified":"2017-06-22T20:57:00","modified_gmt":"2017-06-22T20:57:00","slug":"humanitaere-lage-in-rojava-weiterhin-kritisch-interview","status":"publish","type":"post","link":"https:\/\/www.cadus.org\/en\/artikel\/humanitaere-lage-in-rojava-weiterhin-kritisch-interview\/","title":{"rendered":"Humanit\u00e4re Lage in Rojava weiterhin kritisch &#8211; Interview von Marcus Staiger"},"content":{"rendered":"<div class=\"ce_text block\">\n<p>Das Krankenhaus von Ser\u00ea Kaniy\u00ea wurde gepl\u00fcndert. Alles, was man gebrauchen konnte wurde abgeschraubt und verkauft oder befindet sich heute im Besitz des sogenannten Islamischen Staats. Monatelang war die Stadt, die auf arabisch Ra\u02bes al-\u02bfAin hei\u00dft, von der dschihadistischen Al-Nusra Front besetzt. Eine Bahnlinie trennt sie von ihrer Zwillingsstadt Ceylanp\u0131nar, die auf der anderen Seite der Grenze liegt. In der T\u00fcrkei. Im Juli 2013 gelang es den Truppen der YPG und der YPJ, die 55.000 Einwohner umfassende Gemeinde zu befreien. Die Entwendung der medizinischen Ger\u00e4tschaften durch die islamistischen Banden konnten sie allerdings nicht verhindern. Die Gegend ist ausgeblutet. Nicht nur, dass es an jeder Menge Material fehlt, es mangelt auch an ausgebildetem Personal. \u00dcber die H\u00e4lfte der Bev\u00f6lkerung sind geflohen. Einige wurden get\u00f6tet. \u00c4rzte und \u00c4rztinnen wanderten aus, um in Europa ihr Gl\u00fcck zu finden. Krankenpfleger und Schwestern ebenfalls. Wer will es ihnen verdenken. Diejenigen, die zur\u00fcckbleiben sind m\u00fcde.<\/p>\n<p>Ch., sitzt in einer Baracke neben dem Krankenhaus, in der ein notd\u00fcrftiger Operationssaal eingerichtet ist. Im Krankenhaus selbst befinden sich nur noch einige Schlafs\u00e4le f\u00fcr Patienten. Dicke Tr\u00e4nens\u00e4cke h\u00e4ngen unter seinen freundlichen Augen und tiefe Falten haben sich in sein Gesicht gegraben. Kurz vor unserem Gespr\u00e4ch hat er noch einen K\u00e4mpfer des IS behandelt. Ein junger Mann, der in Handschellen und einer Jacke \u00fcber dem Kopf an uns vorbei gef\u00fchrt wurde. Alle, die im Innenhof der Krankenstation herum standen, wollten ihn sehen. F\u00fcr Ch. war er aber lediglich ein Kranker, der seine Hilfe brauchte. Also hat er ihm geholfen. Wie jedem. Wie immer. Selbst in der Zeit der Besatzung durch Al-Nusra war Ch. in der Stadt und ging nicht weg. Zusammen mit seinem Freund An., einem An\u00e4sthesisten, hielt er die Stellung, behandelte Patienten und operierte. In den Zeiten, als die kurdischen Kr\u00e4fte ihre Offensive starteten und die Gefechte an Heftigkeit zunahmen, gingen sie gar nicht mehr nach Hause. Da legte Ch. das Skalpell \u00fcberhaupt nicht mehr aus der Hand und An. versuchte die verwundeten K\u00e4mpfer zu bet\u00e4uben, so gut es eben ging. Auch heute ist es noch so, wenn wieder einmal eine milit\u00e4rische Operation ansteht. Schlie\u00dflich ist die Klinik von Ser\u00ea Kaniy\u00ea, neben einigen, gut versteckten und teuren Privatkliniken, das einzige \u00f6ffentliche Krankenhaus weit und breit und zust\u00e4ndig f\u00fcr das gesamte Hinterland. Erst in Qamishlo, das \u00fcber hundert Kilometer weit im Osten liegt, gibt es wieder eine entsprechende Versorgung und selbst aus dem zerbombten Koban\u00ea, das fast 200 Kilometer weiter westlich liegt, m\u00fcssen die Menschen hierher gebracht werden. In zehn Minuten steht eine weitere Blinddarmoperation an. An., der An\u00e4sthesist kommt herein und setzt sich zu uns. Die beiden \u00c4rzte greifen zur Zigarette. Sie rauchen Kette. Sie rauchen wie nebenher und trotzdem mit Genuss und einer gewissen Todesverachtung. Vielleicht liegt es daran, dass man morgen ohnehin schon tot sein kann, vielleicht liegt es auch daran, dass das Rauchen unter der Herrschaft der Dschihadisten verboten war. Rauchen ist revolution\u00e4r und es sieht fast so aus, als m\u00fcsse man noch viel mehr rauchen, damit die Revolution siegt.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Wenn man das gesehen hat, was ich gesehen habe, dann reicht rauchen nicht. Dann muss man noch ganz andere Sachen machen.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Was haben Sie denn gesehen?\u00a0\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Zu viele Verletzte. Zu viele Tote. Zu viel Blut. Wir arbeiten hier unter schwierigsten Bedingungen. Das Krankenhaus wurde von Al-Nusra besetzt, die alle Teile verkauft haben, die sich verkaufen lie\u00dfen und das, was sie nicht verkaufen konnten, zerst\u00f6rt haben. Den Rest, den wir noch finden konnten, den haben wir hierher in diese Baracke gebracht. Wenn Ger\u00e4te kaputt gehen, dann m\u00fcssen wir versuchen, die selbst wieder zusammen zu flicken.\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Wir wissen ja, dass keine neuen Ger\u00e4te von au\u00dfen kommen, da muss man dann improvisieren. Das machen wir.<\/p>\n<p>\u00a0<\/p>\n<p>Wie sieht das konkret aus?<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Ein Beispiel, wenn jemand hier ankommt, mit einem Knochenbruch, wo der Knochen, nicht mehr an der richtigen Stelle sitzt und wir ihn zur\u00fcck in die richtige Position bringen m\u00fcssen, dann braucht man normalerweise ein kleines R\u00f6ntgenger\u00e4t, mit dem man sofort sehen kann, ob der Knochen wieder dort sitzt, wo er hingeh\u00f6rt. Hier gibt es das nicht. Wir biegen das hin und dann muss der Patient zum R\u00f6ntgen. Dann k\u00f6nnen wir sehen, ob wir es richtig gemacht habe. Wenn es nicht gut gelungen ist, dann wieder zur\u00fcck und wieder von vorn. Bei einem Fall mussten wir bestimmt 50 mal r\u00f6ntgen. Alle stehen da drum herum. Klick. Ne, noch ein bisschen weiter nach rechts, klick. Nochmal, nochmal. Und das alles mit diesem riesigen R\u00f6ntgenger\u00e4t. Der Typ hatte am Schluss wieder heile Knochen, aber vielleicht auch Hodenkrebs.<\/p>\n<p>\u00a0<\/p>\n<p>Hatte er keine Bleiweste an?<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Ach Quatsch, das machen wir drei\u00dfig Jahre schon so. Au\u00dferdem haben wir keine. Also, was sollen wir machen. \u00a0\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Trotzdem kommen sehr viele Leute hierher.<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Das Krankenhaus hier ist das beste in der Umgebung. Wir haben hier wenigstens rund um die Uhr Strom. In den anderen Krankenh\u00e4usern, die es noch gab, gibt es keinen Strom, nichts.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Wie viele Stunden arbeiten Sie hier am Tag?\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>An.: 24 Stunden. Immer. Wenn wir nach Hause gehen und gerufen werden, kommen wir zur\u00fcck. Wir sind jederzeit abrufbereit.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Sind sie der einzige An\u00e4sthesist hier?\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>An.: Ja. Zwei Assistenten werden jetzt gerade angelernt. Einer von ihnen war die ganze Zeit an der Front.\u00a0\u00a0<\/p>\n<p>Eigentlich arbeiten wir An\u00e4sthesisten und die Chirurgen immer gegeneinander. Aber bei den Operationen m\u00fcssen wir zusammen arbeiten. Zum Gl\u00fcck sind wir schon so lange ein Team.<\/p>\n<p>\u00a0<\/p>\n<p>Ch: Ich und Abu J. arbeiten schon seit Jahren zusammen und in ganz vielen F\u00e4llen ist es so, dass man als Chirurg und An\u00e4sthesist im OP unterschiedlicher Meinung ist. Bei uns ist das nicht der Fall. Wir arbeiten seit Jahren zusammen und verstehen uns hervorragend. Wir sind auch zusammen aufgewachsen und kennen uns schon seit wir Kinder sind. Wir haben zusammen Fu\u00dfball gespielt. Ich war der Torwart und er war St\u00fcrmer. Damals haben wir uns erg\u00e4nzt und heut erg\u00e4nzen wir uns auch. Wenn er merkt, dass es mir w\u00e4hrend der OP nicht so gut geht, dann erz\u00e4hlt er mir einen Witz und bringt mich zum Lachen und andersrum genauso. Wenn ich OPs mache, achte ich auch auf ihn und gucke, ob alles stimmt.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>An.: Und wenn wir beide fertig sind, dann gehen wir raus und trinken einen Wodka zusammen. Dann l\u00e4uft das schon wieder.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Ich frage ihn auch, wenn ich eine Entscheidung treffen muss und hole mir Rat bei ihm. Ich vertraue ihm. Er hat ja auch Erfahrung und bei verschiedenen Chirurgen gearbeitet. Wenn ich ihn frage, wie wir dies oder jenes am besten machen sollen, dann hat er bestimmt auch eine Vorstellung davon, wie man so etwas macht, weil er es bei irgendeinem Kollegen schon mal gesehen hat. Daher ist es mir auch wichtig, dass er dabei ist.\u00a0\u00a0\u00a0<\/p>\n<p>Wenn w\u00e4hrend der Gefechte ein K\u00e4mpfer oder eine K\u00e4mpferin eingeliefert wird und irgendein Organ getroffen ist und ich nicht genau wei\u00df, was ich machen muss, dann k\u00f6nnte ich nat\u00fcrlich in irgendeinem Buch nachschauen, wie man das am besten behandelt, aber in der Praxis sieht das oft ganz anders aus. In der Praxis gibt es sehr unterschiedliche Arten, die Dinge anzugehen, die verschiedenen Chirurgen arbeiten sehr unterschiedlich. Insofern ist mein Kollege sehr wichtig, weil er viele Sachen gesehen hat. So etwas ist oft mehr wert, als das, was in B\u00fcchern steht. Schussverletzungen sind eben oft eine ganz andere Situation als die, die in den B\u00fcchern beschreiben werden.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Was ist das Spezielle an der Kriegssituation?\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Wir sind mit sehr vielen Verletzungen konfrontiert, auf die ich im Rahmen meines Studiums gar nicht vorbereitet wurde, aber weil es die Situation erfordert, m\u00fcssen wir es halt machen. Wir haben hier eine Menge Operationen durchgef\u00fchrt, von denen wir \u00fcberhaupt keine Ahnung hatten, wie wir das machen sollen. Dann liegen die Leute aber hier, und wir m\u00fcssen ihnen helfen und dann machen wir das halt. Die schwierigsten Sachen sind Verletzungen im Bauch oder Brustbereich. Da sto\u00dfen wir regelm\u00e4\u00dfig an unsere Grenzen. Oder wenn die Menschen am Dickdarm verletzt sind, wo wir immer wieder aufs Neue \u00fcberlegen m\u00fcssen, ob wir es so lassen, n\u00e4hen wir es wieder zusammen oder schneiden wir es ab? Das lernen wir alles aus der Praxis. Auf den Krieg ist ja kaum jemand vorbereitet.\u00a0\u00a0<\/p>\n<p>Gerade diese Verletzungen, die im Krieg passieren, sind sehr schwierig zu operieren. So eine Gewehrkugel oder Bombensplitter betreffen ja dann meistens mehrere Partien im K\u00f6rper. Sie betreffen meistens mehrere Organe und man wei\u00df auf den ersten Blick nicht, was alles zu tun ist. Meistens k\u00f6nnen wir erst hier auf dem OP-Tisch herausfinden, was der Verletzte hat und dann muss man sofort handeln. Da wird ja am Telefon nicht gesagt, dass da jetzt jemand kommt, mit dem und dem Krankheitsbild, auf das man sich dann in aller Ruhe vorbereiten kann. Das muss ja dann alles ganz schnell gehen. Man bekommt denjenigen auf den Tisch. Muss sehen, was los ist und dann sofort handeln.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Wie weit gehen Sie bei Ihren Operationen?<\/p>\n<p>\u00a0<\/p>\n<p>Wenn es n\u00f6tig ist, dann entfernen wir hier aber auch Organe. Wir haben hier auch schon Nieren entfernt. Das geh\u00f6rt ja \u00fcberhaupt nicht in meinen Fachbereich. Generell ist es aber so, dass es hier sehr wenige Arzneimittel gibt und in Kriegszeiten ist es noch schlimmer. Manchmal sind die einfachsten Sachen wie Tramodol nicht verf\u00fcgbar. Viele Patienten haben sehr viel Blut verloren und es gab keine Bluttransfusionen. Wir konnten auch nicht den weiten Weg bis nach Qamishlo gehen, weil die Wege teilweise abgeschnitten waren. Das hei\u00dft, dass wir hier vor Ort nach M\u00f6glichkeiten gesucht haben und teilweise haben die Leute, die hier arbeiten und wir selbst Blut gespendet, um Leben zu retten. Es gab hier mehrere Situationen, in denen wir selbst Blut gespendet haben, bevor wir die Operation durchgef\u00fchrt haben, um direkt nach der OP wieder Blut zu spenden.<\/p>\n<p>Das ist die Situation im Krieg: Wenige M\u00f6glichkeiten, aber diese wenigen M\u00f6glichkeiten nutzen, um Leben zu retten.<\/p>\n<p>\u00a0<\/p>\n<p>Wie wichtig ist ihr Team?\u00a0\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Aus meiner Perspektive kann ich sagen, dass die Arbeit, die hier geleistet wird, sehr gut verl\u00e4uft und alle Menschen, die hier arbeiten alles geben. Es gibt zwei An\u00e4sthesisten hier, es gibt einen Helfer im OP, der Arbeiten \u00fcbernimmt. Wir alle arbeiten gemeinsam und wir alle haben das hier zusammen aufgebaut. Wir arbeiten hier als Gruppe und begreifen uns auch als Gruppe. Das geht auch nur zusammen. Als Einzelperson kann man das hier nicht machen.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Viele \u00c4rzte sind gegangen, warum sind Sie geblieben?\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ch: Ich bin hier geblieben, weil ich genau wei\u00df, dass ich gerade im Krieg gebraucht werde. Au\u00dferdem ist hier meine Heimat ist, mein Boden, meine Leute und meine Bev\u00f6lkerung, die hier vor Ort ist. Und deshalb habe ich mich entschlossen, hier zu bleiben und diesen Menschen zu helfen. Ich wei\u00df nicht, warum die meisten anderen \u00c4rzte gegangen und von hier geflohen sind. Nat\u00fcrlich hatten sie alle sehr unterschiedliche Gr\u00fcnde, aber ich bin eben hier geblieben.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Sind sie entt\u00e4uscht von den anderen \u00c4rzten?\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Ich kann es nicht beurteilen. Ich kenne ihre Gr\u00fcnde nicht. Vielleicht hatten sie Angst? Wollten sie ein besseres Leben? Vielleicht waren sie auch nicht besonders patriotisch? Aber im Endeffekt kann ich es nicht beurteilen.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Sie wollten ihre Heimat nicht im Stich lassen?<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Es gibt ein russisches Sprichwort, das lautet: Die Heimat ist wie die Mutter. Ich aber w\u00fcrde sogar sagen, dass die Heimat \u00fcber der Mutter steht. Eine Mutter hat das Kind neun Monate im Bauch, dann gibt sie ihm anderthalb Jahre lang Milch, dann erzieht sie das Kind vielleicht noch, aber nach ein paar Jahren kann sich das Kind schon frei bewegen und ist nicht mehr so angebunden. Die Heimat aber, hat mich jetzt 52 Jahre lang ern\u00e4hrt. Seit 52 Jahren bin ich an meine Heimat gebunden und deshalb w\u00fcrde ich die Heimat sogar h\u00f6her ansiedeln als die Mutter.\u00a0\u00a0<\/p>\n<p>Meine Mutter hat acht Kinder, zwei M\u00e4dchen und sechs Jungs. Wir sind eine kleine Familie, aber die Menschen um mich herum, sie alle sind meine Geschwister, meine Br\u00fcder und Schwestern. Deshalb habe ich gesagt, es ist nicht nur meine kleine Familie, die ich nicht verlassen will, sondern alle, die hier sind, sind meine Familie.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>An.: Seitdem wir hier sind, machen wir keinen Unterschied zwischen den Menschen. Egal ob jemand schwarz oder wei\u00df, dick oder d\u00fcnn ist. Ob die Menschen von hier sind oder nicht. Wir machen keine Unterschiede. Es ist ja sogar so, dass wir hier Anh\u00e4nger von Daesh und sogar Daesh selber hier behandeln. Selbst da machen wir keine Unterschiede. Ich selbst bin Araber. Ich spreche flie\u00dfend Kurdisch. Ich mache keine Unterschiede.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ch: Wir handeln menschlich und behandeln unsere Patienten menschlich.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Wie viele Operationen f\u00fchren Sie hier in der Regel durch?\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Abh\u00e4ngig von der Situation ist es so, dass wir am Tag manchmal zehn OPs hier machen m\u00fcssen, manchmal auch nur eine. Aber ich arbeite ja nicht nur hier. Neben der T\u00e4tigkeit hier, arbeite ich noch in drei privaten Krankenh\u00e4usern und auch dort operiere ich. Im Monat sind das im Durchschnitt 50 bis 60 OPs, die ich mache. Wenn es Gefechte gibt und viele Verletzte hierher kommen, dann sind wir hier manchmal f\u00fcr Wochen und nur mit den K\u00e4mpferinnen und K\u00e4mpfern besch\u00e4ftigt. Wenn es keine Kriegssituation gibt, dann k\u00fcmmern wir uns mehrheitlich um zivile Patienten.<\/p>\n<p>\u00a0<\/p>\n<p>Sind Sie manchmal m\u00fcde?\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>An.: Wenn wir nichts zu tun haben, dann merken wir, wie m\u00fcde wir sind.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Manchmal wurden hier K\u00e4mpfer eingeliefert, bei denen von Anfang an gesagt wurde, dass sie keine \u00dcberlebenschance h\u00e4tte und immer wieder waren welche dabei, die es doch \u00fcberlebt haben. Sehr viele haben \u00fcberlebt, weil wir sie retten konnten. Viele von denen sind auch wieder an die Front zur\u00fcckgegangen oder arbeiten heute in anderen Strukturen. In so vielen Situationen gibt es doch immer wieder Hoffnung, dass die Menschen dann doch \u00fcberleben und durch eine Operation hier bei uns gerettet werden k\u00f6nnen. Situationen, in denen andere gesagt haben, das alles vorbei sei. Ich glaube bis zuletzt. Ich gebe die Hoffnung nie auf.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Glauben Sie auch an das System, das hier in Rojava aufgebaut wird.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Ja. Ich glaube daran, dass es funktionieren wird, weil es ein gemeinschaftliches System ist und weil einzelne Menschen alleine nicht \u00fcberleben k\u00f6nnen. Wir hier in diesem Krankenhaus, wir k\u00f6nnen nicht alleine arbeiten. Ich glaube an den Geist der Kollektivit\u00e4t. In diesem kommunalen Zusammenleben, das wir hier aufbauen, erg\u00e4nzen wir uns in unserer Arbeit vor Ort. Ich kann ja auch nicht sagen, ich bin der Chirurg und deshalb arbeite ich alleine. Dann w\u00fcrde ich nichts schaffen. Der An\u00e4sthesist und der Krankenhelfer und die Krankenschwester haben genauso ihren Anteil an dieser Leistung und sie sind auch mit verantwortlich daf\u00fcr, dass dieses Ergebnis zustande kommt. Aus diesem Grund vergesse ich auch sehr oft, dass ich ein Diplom und studiert habe und daraus anscheinend ein gewisser Status erw\u00e4chst. Diesen Status vergesse ich total, denn wenn ich hier reinkomme, weil ich dann eben, wie alle anderen auch, einfach nur hier bin. Egal ob Krankenschwester oder Reinigungskraft. Wir sind alle gleich und genauso sehe ich das auch gesellschaftlich und sage: Jemand, der auf der Stra\u00dfe sauber macht, k\u00f6nnte genauso auch ein Arzt sein. Diese Statusgedanken legen wir hier ab und diese Klassenunterschiede ebnen wir ein und wir kennen auch nicht diese Art von Hierarchie, wie sie in westlichen Krankenh\u00e4usern anscheinend \u00fcblich ist.\u00a0\u00a0<\/p>\n<p>Wir werden Erfolg haben. Wir werden mit dem Geist der Kollektiv Erfolg haben. ich gebe, was ich geben kann.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Was w\u00fcnschen Sie sich am meisten vom Ausland? Was ist Ihr Appell an die Welt?\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ch.: Mein Appell ist, dass die Menschen, die Rojava verlassen haben, wieder zur\u00fcck kommen, um Rojava wieder aufzubauen. Klar werden wir und die Leute, die zur\u00fcck kommen, in den ersten zwei, drei Jahren Schwierigkeiten haben beim Aufbau, aber wir wissen, dass es auch wieder gute Zeiten geben wird. Deshalb ist mein Appell, dass die Menschen wieder zur\u00fcckkommen.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Vielen Dank f\u00fcr Ihre Zeit.<\/p>\n<p>Photo credits: Marcus Staiger<\/p>\n<\/div>\n<p class=\"info\">Ver\u00f6ffentlicht: <time datetime=\"2016-11-08T17:28:00+01:00\">08.11.2016<\/time><br \/>Verfasser*in:  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Rahmen unseres Ausbildungsprogramms f\u00fcr Paramedics in Nordsyrien ergab sich diesen Sommer die Gelegenheit mit den letzten verbliebenen \u00c4rzten in Serekaniye ein Interview zu f\u00fchren. Lest mehr \u00fcber die Lage im letzten Krankenhaus weit und breit, \u00fcber den Revolutionscharakter von Zigaretten und warum die beiden nicht \u2026<\/p>\n","protected":false},"author":7,"featured_media":9177,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[80,82],"tags":[],"class_list":["post-9179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artikel","category-blog"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/posts\/9179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/comments?post=9179"}],"version-history":[{"count":0,"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/posts\/9179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/media\/9177"}],"wp:attachment":[{"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/media?parent=9179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/categories?post=9179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cadus.org\/en\/wp-json\/wp\/v2\/tags?post=9179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}